{"id":29,"date":"2022-07-15T12:45:46","date_gmt":"2022-07-15T10:45:46","guid":{"rendered":"https:\/\/aula-testing.ch\/?page_id=29"},"modified":"2026-07-01T10:15:43","modified_gmt":"2026-07-01T08:15:43","slug":"team-guisan","status":"publish","type":"page","link":"https:\/\/aula-jugendlager.ch\/main\/it\/team-guisan\/","title":{"rendered":"Team Guisan"},"content":{"rendered":"<div class=\"wp-block-aula-team-card\" style=\"--primary-color: #8a32a7; --accent-color: #8a32a7; --text-color: #333333; --overlay-text-color: #FFFFFF;\">\n        <!-- Main Card -->\n        <div class=\"atc-main-card\">\n            <!-- Hero Section -->\n            <div class=\"atc-hero-section\">\n                                    <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_9545-scaled.jpeg\" \n                         alt=\"Team Guisan\" \n                         class=\"atc-hero-image\">\n                                <div class=\"atc-hero-overlay\">\n                    <h1 class=\"atc-hero-title\">Team Guisan<\/h1>\n                <\/div>\n            <\/div>\n            \n            <!-- Content -->\n            <div class=\"atc-content\">\n                <!-- Activities List -->\n                                <div class=\"atc-activities-section\">\n                                        <p class=\"atc-activities-intro\">Team Guisan offre il programma completo di formazione al Primo Soccorso dal livello 1 al 3 in francese. Dalla formazione di base con corso di pronto soccorso al livello avanzato fino al livello 3 - vi accompagniamo attraverso l'intero programma IVR.<\/p>\n                                        \n                    <div class=\"atc-activities-list\">\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Primo Soccorso Livello 1 IVR (corso di pronto soccorso)<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Corsi in francese<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Corso di base con rianimazione (BLS-AED-SRC). Conforme ad ASTRA, patente valida per 6 anni per il test di scooter e auto.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Primo soccorso livello 2 IVR<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Corsi in francese<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Corso avanzato con rianimazione (BLS-AED-SRC). Prerequisito: Primo soccorso livello 1 IVR<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Primo soccorso livello 3 IVR<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Corsi in francese<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Corso avanzato con formazione infermieristica di base ed esame finale. Prerequisito: Primo Soccorso Livello 2 IVR, et\u00e0 minima 15 anni.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n                                \n                <!-- Info Box -->\n                                \n                <!-- Gallery -->\n                                <div class=\"atc-gallery-section\">\n                    <h2 class=\"atc-gallery-heading\">Impressioni<\/h2>\n                    <div class=\"atc-gallery-grid\">\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_6887-scaled.jpg\" \n                                 alt=\"Galeriebild 1\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Immagine 1 di 3                                <\/span>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_9564-scaled.jpeg\" \n                                 alt=\"Galeriebild 2\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Immagine 2 di 3                                <\/span>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_6561-scaled.jpg\" \n                                 alt=\"Galeriebild 3\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Immagine 3 di 3                                <\/span>\n                            <\/div>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n                            <\/div>\n            \n            <!-- Downloads Section - Inside Card -->\n                        <div class=\"atc-downloads-section\">\n                <h2 class=\"atc-downloads-title\">\n                    <svg class=\"atc-downloads-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                        <path fill-rule=\"evenodd\" d=\"M3 17a1 1 0 011-1h12a1 1 0 110 2H4a1 1 0 01-1-1zm3.293-7.707a1 1 0 011.414 0L9 10.586V3a1 1 0 112 0v7.586l1.293-1.293a1 1 0 111.414 1.414l-3 3a1 1 0 01-1.414 0l-3-3a1 1 0 010-1.414z\" clip-rule=\"evenodd\"\/>\n                    <\/svg>\n                    Scaricamento                <\/h2>\n                \n                                                        <div class=\"atc-download-group\">\n                                                <h3 class=\"atc-download-category\">Regolamenti Guisan<\/h3>\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2023\/07\/Aide-a-soi-meme-et-au-camarade-59_005_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    Aiuto a se stessi e al compagno 59_005_f                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2023\/07\/Aiuto-a-se-stesso-e-al-camerata-59_005_i.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    Aiuto a se stesso e al camerata 59_005_i                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2023\/07\/Le-corps-humain-59_041_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    Il corpo umano 59_041_f                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2023\/07\/Instruction-de-base-pour-le-service-sanitaire-59_042_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    Istruzioni di base per il servizio sanitario 59_042_f                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2023\/07\/Istruzione-di-base-per-il-servizio-sanitario-59_042_i.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    Istruzione di base per il servizio sanitario 59_042_i                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                <\/div>\n                    <\/div>\n    <\/div>\n    \n    \n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aula-jugendlager.ch\/main\/it\/downloads\/\">Programmi settimanali, programmi giornalieri e liste delle cose da portare<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":104,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/pages\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":31,"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/pages\/29\/revisions"}],"predecessor-version":[{"id":6794,"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/pages\/29\/revisions\/6794"}],"wp:attachment":[{"href":"https:\/\/aula-jugendlager.ch\/main\/it\/wp-json\/wp\/v2\/media?parent=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}