{"id":41,"date":"2022-07-15T12:48:29","date_gmt":"2022-07-15T10:48:29","guid":{"rendered":"https:\/\/aula-testing.ch\/?page_id=41"},"modified":"2026-07-01T10:16:32","modified_gmt":"2026-07-01T08:16:32","slug":"team-hefti","status":"publish","type":"page","link":"https:\/\/aula-jugendlager.ch\/main\/en\/team-hefti\/","title":{"rendered":"Team Adrien Hefti"},"content":{"rendered":"<div class=\"wp-block-aula-team-card\" style=\"--primary-color: #b72122; --accent-color: #b72122; --text-color: #333333; --overlay-text-color: #FFFFFF;\">\n        <!-- Main Card -->\n        <div class=\"atc-main-card\">\n            <!-- Hero Section -->\n            <div class=\"atc-hero-section\">\n                                    <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_1040-scaled.jpeg\" \n                         alt=\"Team Adrien Hefti\" \n                         class=\"atc-hero-image\">\n                                <div class=\"atc-hero-overlay\">\n                    <h1 class=\"atc-hero-title\">Team Adrien Hefti<\/h1>\n                <\/div>\n            <\/div>\n            \n            <!-- Content -->\n            <div class=\"atc-content\">\n                <!-- Activities List -->\n                                <div class=\"atc-activities-section\">\n                                        <p class=\"atc-activities-intro\">Team Adrien Hefti offers special practical training for advanced first aiders. With a First Aid Level 3 IVR certificate, bivouac, setting up and running a first aid post and spectacular patient loading into the SuperPuma helicopter - first aid becomes an experience.<\/p>\n                                        \n                    <div class=\"atc-activities-list\">\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Bivouac and sport<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Outdoor training<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Practical exercises under field conditions with overnight stay<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Establishment and operation of medical aid station<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Operational organization<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Learn how to professionally set up and operate a first-aid post<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-activity-item\">\n                            <div class=\"atc-activity-header\">\n                                <svg class=\"atc-activity-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                    <path fill-rule=\"evenodd\" d=\"M10 18a8 8 0 100-16 8 8 0 000 16zm3.707-9.293a1 1 0 00-1.414-1.414L9 10.586 7.707 9.293a1 1 0 00-1.414 1.414l2 2a1 1 0 001.414 0l4-4z\" clip-rule=\"evenodd\"\/>\n                                <\/svg>\n                                <div class=\"atc-activity-content\">\n                                    <h3 class=\"atc-activity-title\">Patient loading SuperPuma<\/h3>\n                                                                        <p class=\"atc-activity-subtitle\">Helicopter training<\/p>\n                                                                                                            <p class=\"atc-activity-description\">Practical exercise on the professional loading of patients into a SuperPuma helicopter.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n                                \n                <!-- Info Box -->\n                                <div class=\"atc-info-box\">\n                                        <svg class=\"atc-info-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                        <path fill-rule=\"evenodd\" d=\"M18 10a8 8 0 11-16 0 8 8 0 0116 0zm-7-4a1 1 0 11-2 0 1 1 0 012 0zM9 9a1 1 0 000 2v3a1 1 0 001 1h1a1 1 0 100-2v-3a1 1 0 00-1-1H9z\" clip-rule=\"evenodd\"\/>\n                    <\/svg>\n                                        <p class=\"atc-info-text\">Prerequisites: Successful completion of Team 3 (Huber-Hotz) and minimum age 16 years. This special training prepares you for demanding missions and work in emergency medical services.<\/p>\n                <\/div>\n                                \n                <!-- Gallery -->\n                                <div class=\"atc-gallery-section\">\n                    <h2 class=\"atc-gallery-heading\">Impressions<\/h2>\n                    <div class=\"atc-gallery-grid\">\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_6402-scaled.jpg\" \n                                 alt=\"Galeriebild 1\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Picture 1 of 4                                <\/span>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_5807-scaled.jpg\" \n                                 alt=\"Galeriebild 2\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Picture 2 of 4                                <\/span>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_5708-scaled.jpg\" \n                                 alt=\"Galeriebild 3\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Picture 3 of 4                                <\/span>\n                            <\/div>\n                        <\/div>\n                                                <div class=\"atc-gallery-item\">\n                            <img decoding=\"async\" src=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/IMG_1040-scaled.jpeg\" \n                                 alt=\"Galeriebild 4\" \n                                 class=\"atc-gallery-image\"\n                                 loading=\"lazy\">\n                            <div class=\"atc-gallery-overlay\">\n                                <span class=\"atc-gallery-caption\">\n                                    Picture 4 of 4                                <\/span>\n                            <\/div>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n                            <\/div>\n            \n            <!-- Downloads Section - Inside Card -->\n                        <div class=\"atc-downloads-section\">\n                <h2 class=\"atc-downloads-title\">\n                    <svg class=\"atc-downloads-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                        <path fill-rule=\"evenodd\" d=\"M3 17a1 1 0 011-1h12a1 1 0 110 2H4a1 1 0 01-1-1zm3.293-7.707a1 1 0 011.414 0L9 10.586V3a1 1 0 112 0v7.586l1.293-1.293a1 1 0 111.414 1.414l-3 3a1 1 0 01-1.414 0l-3-3a1 1 0 010-1.414z\" clip-rule=\"evenodd\"\/>\n                    <\/svg>\n                    Downloads                <\/h2>\n                \n                                                        <div class=\"atc-download-group\">\n                                                <h3 class=\"atc-download-category\">Regulations Team Adrien Hefti<\/h3>\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_005_d-1.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59,005 D Self-help and comradeship                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_005_f-1.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.005 F Aide \u00e0 soi-m\u00eame et au camarade                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_005_i-1.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.005 I Aiuto a se stesso e al camerata                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                                            <div class=\"atc-download-group\">\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_041_d.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59,041 D The human body                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_041_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.041 F Le corps humain                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                                            <div class=\"atc-download-group\">\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_042_d.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59,042 D Primary school for medical services                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_042_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.042 F Instruction de base pour le service sanitaire                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_042_i.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.042 I Istruzione di base per il servizio sanitario                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                                            <div class=\"atc-download-group\">\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_110_d.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.110 D The medical aid station                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_110_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.110 F Le poste de secours sanitaire                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                                            <div class=\"atc-download-group\">\n                                                \n                        <div class=\"atc-download-items\">\n                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_123_d.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.123 D Injection, infusion, blood sampling                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_123_f.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.123 F Injection, perfusion et prise de sang                                <\/a>\n                                                                                                                            <a href=\"https:\/\/aula-jugendlager.ch\/main\/wp-content\/uploads\/sites\/8\/2025\/06\/59_123_i.pdf\" \n                                   class=\"atc-download-link\" \n                                   target=\"_blank\"\n                                   download>\n                                    <svg class=\"atc-download-icon\" fill=\"currentColor\" viewbox=\"0 0 20 20\">\n                                        <path d=\"M9 2a1 1 0 000 2h2a1 1 0 100-2H9z\"\/>\n                                        <path fill-rule=\"evenodd\" d=\"M4 5a2 2 0 012-2 1 1 0 000 2H6a2 2 0 00-2 2v6a2 2 0 002 2h8a2 2 0 002-2V7a2 2 0 00-2-2h-1a1 1 0 100-2h1a4 4 0 014 4v6a4 4 0 01-4 4H6a4 4 0 01-4-4V7a4 4 0 014-4z\" clip-rule=\"evenodd\"\/>\n                                    <\/svg>\n                                    59.123 I Iniezione, infusione e prelievo ematico                                <\/a>\n                                                                                    <\/div>\n                    <\/div>\n                                                <\/div>\n                    <\/div>\n    <\/div>\n    \n    \n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/aula-jugendlager.ch\/main\/en\/downloads\/\">Weekly Schedules, Daily Schedules, and Packing Lists<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":105,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":34,"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":6795,"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/pages\/41\/revisions\/6795"}],"wp:attachment":[{"href":"https:\/\/aula-jugendlager.ch\/main\/en\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}